{"id":4289,"date":"2022-05-02T17:55:10","date_gmt":"2022-05-02T17:55:10","guid":{"rendered":"https:\/\/elys.eu\/nos-prestations\/stockage\/"},"modified":"2022-09-08T08:15:52","modified_gmt":"2022-09-08T08:15:52","slug":"battery-storage","status":"publish","type":"page","link":"https:\/\/elys.eu\/en\/our-services\/battery-storage\/","title":{"rendered":"Battery storage"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":4187,"parent":4270,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"templates\/services.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4289","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Battery storage - Elys<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Battery storage - Elys\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elys.eu\/en\/our-services\/battery-storage\/\" \/>\n<meta property=\"og:site_name\" content=\"Elys\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-08T08:15:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elys.eu\/wp-content\/uploads\/2022\/05\/SW_Stockage_Desirade-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elys.eu\\\/en\\\/our-services\\\/battery-storage\\\/\",\"url\":\"https:\\\/\\\/elys.eu\\\/en\\\/our-services\\\/battery-storage\\\/\",\"name\":\"Battery storage - Elys\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elys.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elys.eu\\\/en\\\/our-services\\\/battery-storage\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elys.eu\\\/en\\\/our-services\\\/battery-storage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elys.eu\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/SW_Stockage_Desirade-1-scaled.jpg\",\"datePublished\":\"2022-05-02T17:55:10+00:00\",\"dateModified\":\"2022-09-08T08:15:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elys.eu\\\/en\\\/our-services\\\/battery-storage\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elys.eu\\\/en\\\/our-services\\\/battery-storage\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/elys.eu\\\/en\\\/our-services\\\/battery-storage\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elys.eu\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/SW_Stockage_Desirade-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/elys.eu\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/SW_Stockage_Desirade-1-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elys.eu\\\/en\\\/our-services\\\/battery-storage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/elys.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Our services\",\"item\":\"https:\\\/\\\/elys.eu\\\/en\\\/our-services\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Battery storage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elys.eu\\\/#website\",\"url\":\"https:\\\/\\\/elys.eu\\\/\",\"name\":\"Elys\",\"description\":\"Sp\u00e9cialiste des projets d&#039;\u00e9nergies renouvelables\",\"publisher\":{\"@id\":\"https:\\\/\\\/elys.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elys.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elys.eu\\\/#organization\",\"name\":\"Elys\",\"url\":\"https:\\\/\\\/elys.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/elys.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elys.eu\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Logo-Elys.jpg\",\"contentUrl\":\"https:\\\/\\\/elys.eu\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Logo-Elys.jpg\",\"width\":381,\"height\":270,\"caption\":\"Elys\"},\"image\":{\"@id\":\"https:\\\/\\\/elys.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/elys\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Battery storage - Elys","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"en_US","og_type":"article","og_title":"Battery storage - Elys","og_url":"https:\/\/elys.eu\/en\/our-services\/battery-storage\/","og_site_name":"Elys","article_modified_time":"2022-09-08T08:15:52+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/elys.eu\/wp-content\/uploads\/2022\/05\/SW_Stockage_Desirade-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elys.eu\/en\/our-services\/battery-storage\/","url":"https:\/\/elys.eu\/en\/our-services\/battery-storage\/","name":"Battery storage - Elys","isPartOf":{"@id":"https:\/\/elys.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elys.eu\/en\/our-services\/battery-storage\/#primaryimage"},"image":{"@id":"https:\/\/elys.eu\/en\/our-services\/battery-storage\/#primaryimage"},"thumbnailUrl":"https:\/\/elys.eu\/wp-content\/uploads\/2022\/05\/SW_Stockage_Desirade-1-scaled.jpg","datePublished":"2022-05-02T17:55:10+00:00","dateModified":"2022-09-08T08:15:52+00:00","breadcrumb":{"@id":"https:\/\/elys.eu\/en\/our-services\/battery-storage\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elys.eu\/en\/our-services\/battery-storage\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/elys.eu\/en\/our-services\/battery-storage\/#primaryimage","url":"https:\/\/elys.eu\/wp-content\/uploads\/2022\/05\/SW_Stockage_Desirade-1-scaled.jpg","contentUrl":"https:\/\/elys.eu\/wp-content\/uploads\/2022\/05\/SW_Stockage_Desirade-1-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/elys.eu\/en\/our-services\/battery-storage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/elys.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Our services","item":"https:\/\/elys.eu\/en\/our-services\/"},{"@type":"ListItem","position":3,"name":"Battery storage"}]},{"@type":"WebSite","@id":"https:\/\/elys.eu\/#website","url":"https:\/\/elys.eu\/","name":"Elys","description":"Sp\u00e9cialiste des projets d&#039;\u00e9nergies renouvelables","publisher":{"@id":"https:\/\/elys.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elys.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/elys.eu\/#organization","name":"Elys","url":"https:\/\/elys.eu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/elys.eu\/#\/schema\/logo\/image\/","url":"https:\/\/elys.eu\/wp-content\/uploads\/2021\/11\/Logo-Elys.jpg","contentUrl":"https:\/\/elys.eu\/wp-content\/uploads\/2021\/11\/Logo-Elys.jpg","width":381,"height":270,"caption":"Elys"},"image":{"@id":"https:\/\/elys.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/elys\/"]}]}},"_links":{"self":[{"href":"https:\/\/elys.eu\/en\/wp-json\/wp\/v2\/pages\/4289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elys.eu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elys.eu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elys.eu\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elys.eu\/en\/wp-json\/wp\/v2\/comments?post=4289"}],"version-history":[{"count":11,"href":"https:\/\/elys.eu\/en\/wp-json\/wp\/v2\/pages\/4289\/revisions"}],"predecessor-version":[{"id":4620,"href":"https:\/\/elys.eu\/en\/wp-json\/wp\/v2\/pages\/4289\/revisions\/4620"}],"up":[{"embeddable":true,"href":"https:\/\/elys.eu\/en\/wp-json\/wp\/v2\/pages\/4270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elys.eu\/en\/wp-json\/wp\/v2\/media\/4187"}],"wp:attachment":[{"href":"https:\/\/elys.eu\/en\/wp-json\/wp\/v2\/media?parent=4289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}