{"id":4286,"date":"2022-05-02T17:54:59","date_gmt":"2022-05-02T17:54:59","guid":{"rendered":"https:\/\/elys.eu\/nos-prestations\/solaire-pv\/"},"modified":"2022-07-04T10:05:44","modified_gmt":"2022-07-04T10:05:44","slug":"energia-solar-fotovoltaica","status":"publish","type":"page","link":"https:\/\/elys.eu\/es\/nuestros-servicios\/energia-solar-fotovoltaica\/","title":{"rendered":"Energ\u00eda Solar Fotovoltaica"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":4175,"parent":4271,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"templates\/services.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4286","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Energ\u00eda Solar Fotovoltaica - Elys<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Energ\u00eda Solar Fotovoltaica - Elys\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elys.eu\/es\/nuestros-servicios\/energia-solar-fotovoltaica\/\" \/>\n<meta property=\"og:site_name\" content=\"Elys\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-04T10:05:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elys.eu\/wp-content\/uploads\/2022\/05\/DJI_0589-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elys.eu\\\/es\\\/nuestros-servicios\\\/energia-solar-fotovoltaica\\\/\",\"url\":\"https:\\\/\\\/elys.eu\\\/es\\\/nuestros-servicios\\\/energia-solar-fotovoltaica\\\/\",\"name\":\"Energ\u00eda Solar Fotovoltaica - Elys\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elys.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elys.eu\\\/es\\\/nuestros-servicios\\\/energia-solar-fotovoltaica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elys.eu\\\/es\\\/nuestros-servicios\\\/energia-solar-fotovoltaica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elys.eu\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/DJI_0589-scaled.jpg\",\"datePublished\":\"2022-05-02T17:54:59+00:00\",\"dateModified\":\"2022-07-04T10:05:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elys.eu\\\/es\\\/nuestros-servicios\\\/energia-solar-fotovoltaica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elys.eu\\\/es\\\/nuestros-servicios\\\/energia-solar-fotovoltaica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elys.eu\\\/es\\\/nuestros-servicios\\\/energia-solar-fotovoltaica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elys.eu\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/DJI_0589-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/elys.eu\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/DJI_0589-scaled.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"DCIM100MEDIADJI_0589.JPG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elys.eu\\\/es\\\/nuestros-servicios\\\/energia-solar-fotovoltaica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/elys.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestros servicios\",\"item\":\"https:\\\/\\\/elys.eu\\\/es\\\/nuestros-servicios\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Energ\u00eda Solar Fotovoltaica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elys.eu\\\/#website\",\"url\":\"https:\\\/\\\/elys.eu\\\/\",\"name\":\"Elys\",\"description\":\"Sp\u00e9cialiste des projets d&#039;\u00e9nergies renouvelables\",\"publisher\":{\"@id\":\"https:\\\/\\\/elys.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elys.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elys.eu\\\/#organization\",\"name\":\"Elys\",\"url\":\"https:\\\/\\\/elys.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elys.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elys.eu\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Logo-Elys.jpg\",\"contentUrl\":\"https:\\\/\\\/elys.eu\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Logo-Elys.jpg\",\"width\":381,\"height\":270,\"caption\":\"Elys\"},\"image\":{\"@id\":\"https:\\\/\\\/elys.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/elys\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Energ\u00eda Solar Fotovoltaica - Elys","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Energ\u00eda Solar Fotovoltaica - Elys","og_url":"https:\/\/elys.eu\/es\/nuestros-servicios\/energia-solar-fotovoltaica\/","og_site_name":"Elys","article_modified_time":"2022-07-04T10:05:44+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/elys.eu\/wp-content\/uploads\/2022\/05\/DJI_0589-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elys.eu\/es\/nuestros-servicios\/energia-solar-fotovoltaica\/","url":"https:\/\/elys.eu\/es\/nuestros-servicios\/energia-solar-fotovoltaica\/","name":"Energ\u00eda Solar Fotovoltaica - Elys","isPartOf":{"@id":"https:\/\/elys.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elys.eu\/es\/nuestros-servicios\/energia-solar-fotovoltaica\/#primaryimage"},"image":{"@id":"https:\/\/elys.eu\/es\/nuestros-servicios\/energia-solar-fotovoltaica\/#primaryimage"},"thumbnailUrl":"https:\/\/elys.eu\/wp-content\/uploads\/2022\/05\/DJI_0589-scaled.jpg","datePublished":"2022-05-02T17:54:59+00:00","dateModified":"2022-07-04T10:05:44+00:00","breadcrumb":{"@id":"https:\/\/elys.eu\/es\/nuestros-servicios\/energia-solar-fotovoltaica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elys.eu\/es\/nuestros-servicios\/energia-solar-fotovoltaica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elys.eu\/es\/nuestros-servicios\/energia-solar-fotovoltaica\/#primaryimage","url":"https:\/\/elys.eu\/wp-content\/uploads\/2022\/05\/DJI_0589-scaled.jpg","contentUrl":"https:\/\/elys.eu\/wp-content\/uploads\/2022\/05\/DJI_0589-scaled.jpg","width":2560,"height":1920,"caption":"DCIM100MEDIADJI_0589.JPG"},{"@type":"BreadcrumbList","@id":"https:\/\/elys.eu\/es\/nuestros-servicios\/energia-solar-fotovoltaica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/elys.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Nuestros servicios","item":"https:\/\/elys.eu\/es\/nuestros-servicios\/"},{"@type":"ListItem","position":3,"name":"Energ\u00eda Solar Fotovoltaica"}]},{"@type":"WebSite","@id":"https:\/\/elys.eu\/#website","url":"https:\/\/elys.eu\/","name":"Elys","description":"Sp\u00e9cialiste des projets d&#039;\u00e9nergies renouvelables","publisher":{"@id":"https:\/\/elys.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elys.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elys.eu\/#organization","name":"Elys","url":"https:\/\/elys.eu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elys.eu\/#\/schema\/logo\/image\/","url":"https:\/\/elys.eu\/wp-content\/uploads\/2021\/11\/Logo-Elys.jpg","contentUrl":"https:\/\/elys.eu\/wp-content\/uploads\/2021\/11\/Logo-Elys.jpg","width":381,"height":270,"caption":"Elys"},"image":{"@id":"https:\/\/elys.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/elys\/"]}]}},"_links":{"self":[{"href":"https:\/\/elys.eu\/es\/wp-json\/wp\/v2\/pages\/4286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elys.eu\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elys.eu\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elys.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elys.eu\/es\/wp-json\/wp\/v2\/comments?post=4286"}],"version-history":[{"count":7,"href":"https:\/\/elys.eu\/es\/wp-json\/wp\/v2\/pages\/4286\/revisions"}],"predecessor-version":[{"id":4399,"href":"https:\/\/elys.eu\/es\/wp-json\/wp\/v2\/pages\/4286\/revisions\/4399"}],"up":[{"embeddable":true,"href":"https:\/\/elys.eu\/es\/wp-json\/wp\/v2\/pages\/4271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elys.eu\/es\/wp-json\/wp\/v2\/media\/4175"}],"wp:attachment":[{"href":"https:\/\/elys.eu\/es\/wp-json\/wp\/v2\/media?parent=4286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}